{"id":1910,"date":"2018-01-30T14:44:38","date_gmt":"2018-01-30T13:44:38","guid":{"rendered":"http:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie.jpg"},"modified":"2018-01-30T14:44:38","modified_gmt":"2018-01-30T13:44:38","slug":"a-0741-kopie","status":"inherit","type":"attachment","link":"https:\/\/katzenmaiers.de\/blog\/2018\/01\/30\/ohm-beads-nian-nian-you-yu\/a-0741-kopie\/","title":{"rendered":"A-0741 &#8211; Kopie"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1910","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-300x200.jpg 300w, https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-768x512.jpg 768w, https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-1024x683.jpg 1024w, https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-370x247.jpg 370w, https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-1040x693.jpg 1040w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":5184,"height":3456,"file":"2018\/01\/A-0741-Kopie.jpg","sizes":{"thumbnail":{"file":"A-0741-Kopie-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-150x150.jpg"},"medium":{"file":"A-0741-Kopie-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-300x200.jpg"},"medium_large":{"file":"A-0741-Kopie-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-768x512.jpg"},"large":{"file":"A-0741-Kopie-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-1024x683.jpg"},"oblique-entry-thumb":{"file":"A-0741-Kopie-370x247.jpg","width":370,"height":247,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-370x247.jpg"},"oblique-single-thumb":{"file":"A-0741-Kopie-1040x693.jpg","width":1040,"height":693,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie-1040x693.jpg"},"full":{"file":"A-0741-Kopie.jpg","width":5184,"height":3456,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie.jpg"}},"image_meta":{"aperture":"6.3","credit":"","camera":"Canon EOS 60D","caption":"","created_timestamp":"1508923625","copyright":"","focal_length":"60","iso":"400","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]}},"post":1909,"source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/01\/A-0741-Kopie.jpg","_links":{"self":[{"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/media\/1910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/comments?post=1910"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1909,"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/posts\/1909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}