{"id":3026,"date":"2018-06-08T21:18:03","date_gmt":"2018-06-08T19:18:03","guid":{"rendered":"http:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3.jpg"},"modified":"2018-06-08T21:18:03","modified_gmt":"2018-06-08T19:18:03","slug":"elfpetite_doty_04-3","status":"inherit","type":"attachment","link":"https:\/\/katzenmaiers.de\/blog\/2018\/06\/06\/elfpetite-doty-2018-impressions\/elfpetite_doty_04-3\/","title":{"rendered":"Elfpetite_Doty_04 (3)"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3026","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"104\" src=\"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3-300x104.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3-300x104.jpg 300w, https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3-370x128.jpg 370w, https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":207,"file":"2018\/06\/Elfpetite_Doty_04-3.jpg","sizes":{"thumbnail":{"file":"Elfpetite_Doty_04-3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3-150x150.jpg"},"medium":{"file":"Elfpetite_Doty_04-3-300x104.jpg","width":300,"height":104,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3-300x104.jpg"},"oblique-entry-thumb":{"file":"Elfpetite_Doty_04-3-370x128.jpg","width":370,"height":128,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3-370x128.jpg"},"full":{"file":"Elfpetite_Doty_04-3.jpg","width":600,"height":207,"mime_type":"image\/jpeg","source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3.jpg"}},"image_meta":{"aperture":"6.3","credit":"","camera":"NIKON D90","caption":"","created_timestamp":"1528480666","copyright":"","focal_length":"60","iso":"200","shutter_speed":"0.005","title":"","orientation":"1","keywords":[]}},"post":3013,"source_url":"https:\/\/katzenmaiers.de\/blog\/wp-content\/uploads\/2018\/06\/Elfpetite_Doty_04-3.jpg","_links":{"self":[{"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/media\/3026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/comments?post=3026"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3013,"href":"https:\/\/katzenmaiers.de\/blog\/wp-json\/wp\/v2\/posts\/3013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}